{"id":2902,"date":"2019-05-15T15:53:20","date_gmt":"2019-05-15T15:53:20","guid":{"rendered":"http:\/\/zipzapsocial.com\/?p=2902"},"modified":"2019-05-15T16:15:15","modified_gmt":"2019-05-15T16:15:15","slug":"els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma","status":"publish","type":"post","link":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/","title":{"rendered":"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma"},"content":{"rendered":"<p style=\"text-align: justify;\">El general manager de <a href=\"https:\/\/www.rocajunyent.com\/ca\/\">Roca Junyent<\/a> i ex gerent del <a href=\"https:\/\/www.apabcn.cat\/ca_es\/Pagines\/inici.aspx\">Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona<\/a> <strong>Joan Ignasi Soldevilla<\/strong> ha estat el cinqu\u00e8 convidat de <strong>Zip Zap en Forma<\/strong>, una iniciativa de Zip Zap Social pensada perqu\u00e8 el nostre equip conegui de prop i en profunditat els projectes i traject\u00f2ries dels clients i col\u00b7laboradors.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Joan Ignasi Soldevilla ha compartit amb tot l\u2019equip de Zip Zap Social els principals <strong>reptes de la seva traject\u00f2ria professional<\/strong>, marcada els \u00faltims anys per la direcci\u00f3 general o ger\u00e8ncia de diverses organitzacions, entre les quals destaca el Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona. En aquest sentit ha recordat que va ser com a gerent d\u2019aquest col\u00b7legi professional quan va contactar per primera vegada amb Zip Zap Social, encarregant-nos incrementar les matriculacions al grau d\u2019arquitectura t\u00e8cnica a les universitats catalanes. Un repte que varem superar amb solv\u00e8ncia <strong>aconseguint un increment del 60% de matriculacions el primer any <\/strong>i que ara estem realitzant a nivell estatal amb el projecte\u00a0 <a href=\"https:\/\/www.arquitecturatecnicayedificacion.es\/\">\u2018<\/a><a href=\"https:\/\/www.arquitecturatecnicayedificacion.es\/\"><strong>Arquitectura T\u00e9cnica y Edificaci\u00f3n-ATE\u2019<\/strong><\/a><strong>.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En relaci\u00f3 als seus <strong>11 anys al capdavant del Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona<\/strong>, Joan Ignasi Soldevilla ha explicat que \u201cquan vaig comen\u00e7ar el 2008 vaig haver de bregar amb la crisi i la caiguda del sector de la construcci\u00f3 que va afectar molt el Col\u00b7legi, una situaci\u00f3 que varem revertir amb la <strong>introducci\u00f3 de la tecnologia<\/strong>\u201d. Soldevilla tamb\u00e9 ha subratllat que \u201cla prioritat d\u2019un col\u00b7legi professional no \u00e9s generar beneficis sin\u00f3 prestar els millors serveis als seus col\u00b7legiats\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Des de fa uns mesos \u00e9s general manager de Roca Junyent, un dels despatxos d\u2019advocats m\u00e9s reconeguts del nostre pa\u00eds amb m\u00e9s de 240 professionals. Segons Joan Ignasi Soldevilla, <strong>\u201cla clau d\u2019una bona gesti\u00f3 \u00e9s homogene\u00eftzar processos i rodejar-se d\u2019equips responsables i aut\u00f2noms\u201d. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El general manager de Roca Junyent i ex gerent del Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona Joan Ignasi Soldevilla ha estat el cinqu\u00e8 convidat de Zip Zap en Forma, una iniciativa de Zip Zap Social pensada perqu\u00e8&hellip;<\/p>\n","protected":false},"author":3,"featured_media":2896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[110,105],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social\" \/>\n<meta property=\"og:description\" content=\"El general manager de Roca Junyent i ex gerent del Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona Joan Ignasi Soldevilla ha estat el cinqu\u00e8 convidat de Zip Zap en Forma, una iniciativa de Zip Zap Social pensada perqu\u00e8&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/\" \/>\n<meta property=\"og:site_name\" content=\"ZipZap Social\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-15T15:53:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T16:15:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1422\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zipzapsocial.com\/#website\",\"url\":\"https:\/\/zipzapsocial.com\/\",\"name\":\"ZipZap Social\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zipzapsocial.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#primaryimage\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg\",\"contentUrl\":\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg\",\"width\":1422,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#webpage\",\"url\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/\",\"name\":\"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social\",\"isPartOf\":{\"@id\":\"https:\/\/zipzapsocial.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#primaryimage\"},\"datePublished\":\"2019-05-15T15:53:20+00:00\",\"dateModified\":\"2019-05-15T16:15:15+00:00\",\"author\":{\"@id\":\"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1\"},\"breadcrumb\":{\"@id\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/zipzapsocial.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zipzapsocial.com\/#personlogo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g\",\"caption\":\"David\"},\"url\":\"https:\/\/zipzapsocial.com\/ca\/author\/david\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/","og_locale":"ca_ES","og_type":"article","og_title":"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social","og_description":"El general manager de Roca Junyent i ex gerent del Col\u00b7legi d\u2019Aparelladors, Arquitectes T\u00e8nics i Enginyers d\u2019Edificaci\u00f3 de Barcelona Joan Ignasi Soldevilla ha estat el cinqu\u00e8 convidat de Zip Zap en Forma, una iniciativa de Zip Zap Social pensada perqu\u00e8&hellip;","og_url":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/","og_site_name":"ZipZap Social","article_published_time":"2019-05-15T15:53:20+00:00","article_modified_time":"2019-05-15T16:15:15+00:00","og_image":[{"width":1422,"height":800,"url":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"David","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/zipzapsocial.com\/#website","url":"https:\/\/zipzapsocial.com\/","name":"ZipZap Social","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zipzapsocial.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"ImageObject","@id":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#primaryimage","inLanguage":"ca","url":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg","contentUrl":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/05\/Zip-Zap-En-Forma-Joan-Ignasi-Soldevila.jpg","width":1422,"height":800},{"@type":"WebPage","@id":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#webpage","url":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/","name":"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma - ZipZap Social","isPartOf":{"@id":"https:\/\/zipzapsocial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#primaryimage"},"datePublished":"2019-05-15T15:53:20+00:00","dateModified":"2019-05-15T16:15:15+00:00","author":{"@id":"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1"},"breadcrumb":{"@id":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zipzapsocial.com\/ca\/els-reptes-de-la-gestio-empresarial-protagonistes-duna-nova-trobada-de-zip-zap-en-forma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zipzapsocial.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Els reptes de la gesti\u00f3 empresarial, protagonistes d\u2019una nova trobada de Zip Zap En Forma"}]},{"@type":"Person","@id":"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1","name":"David","image":{"@type":"ImageObject","@id":"https:\/\/zipzapsocial.com\/#personlogo","inLanguage":"ca","url":"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g","caption":"David"},"url":"https:\/\/zipzapsocial.com\/ca\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2902\/"}],"collection":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/comments\/?post=2902"}],"version-history":[{"count":4,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2902\/revisions\/"}],"predecessor-version":[{"id":2908,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2902\/revisions\/2908\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/media\/2896\/"}],"wp:attachment":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/media\/?parent=2902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/categories\/?post=2902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/tags\/?post=2902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}