{"id":2881,"date":"2019-04-24T15:55:42","date_gmt":"2019-04-24T15:55:42","guid":{"rendered":"http:\/\/zipzapsocial.com\/?p=2881"},"modified":"2019-04-24T15:56:04","modified_gmt":"2019-04-24T15:56:04","slug":"el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma","status":"publish","type":"post","link":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/","title":{"rendered":"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma"},"content":{"rendered":"<p>El <strong>gerent de <\/strong><a href=\"https:\/\/remmguitart.com\/\"><strong>Remm Guitart<\/strong><\/a><strong> Xavier Mas<\/strong> ha protagonitzat la <strong>quarta trobada de Zip Zap En Forma<\/strong>, una iniciativa perqu\u00e8 el nostre equip conegui de prop i en profunditat els projectes i traject\u00f2ries dels clients i col\u00b7laboradors.<\/p>\n<p>&nbsp;<\/p>\n<p>Fa gaireb\u00e9 3 anys que des de Zip Zap gestionem el m\u00e0rqueting digital de Remm Guitart, els <strong>concessionaris de Renault i Dacia al Baix Llobregat, Anoia, Alt Pened\u00e8s i Garraf<\/strong>. Des de Zip Zap amplifiquem de forma segmentada els missatges que Renault llan\u00e7a per anar m\u00e9s enll\u00e0 de la venda de cotxes. Promovem accions ad hoc i sota demanda sobre les necessitats espec\u00edfiques de cadascuna de les delegacions de Remm Guitart.<\/p>\n<p>&nbsp;<\/p>\n<p>En la seva xerrada amb l&#8217;equip de Zip Zap Social, Xavier Mas ha destacat que Remm Guitart \u00e9s una <strong>empresa familiar creada el 1993 <\/strong>amb una gesti\u00f3 professionalitzada. A m\u00e9s ha afegit que &#8220;cada seu t\u00e9 les seves pr\u00f2pies circumst\u00e0ncies i caracter\u00edstiques&#8221; i ha remarcat que &#8220;<strong>\u00e9s clau tenir en compte que el p\u00fablic objectiu de la zona de l&#8217;Anoia \u00e9s molt diferent al del Baix Llobregat<\/strong>&#8220;. En aquest sentit ha apuntat que &#8220;el valor afegit de Remm Guitart \u00e9s justament la<strong> vinculaci\u00f3 al territori<\/strong>, aix\u00ed com tamb\u00e9 la nostra aposta per la cultura&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>En relaci\u00f3 al funcionament de la ind\u00fastria automobil\u00edstica, Xavier Mas ha subratllat que &#8220;la ind\u00fastria de components i els distribu\u00efdors depenem sempre dels fabricants&#8221; i ha assenyalat que \u201c<strong>els concessionaris venem el que les marques fabriquen, no a l&#8217;inrev\u00e9s<\/strong>&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalment, Xavier Mas ha apuntat que &#8220;el futur vindr\u00e0 marcat pel paper del vehicle el\u00e8ctric i les noves formes de mobilitat com el car sharing&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gerent de Remm Guitart Xavier Mas ha protagonitzat la quarta trobada de Zip Zap En Forma, una iniciativa perqu\u00e8 el nostre equip conegui de prop i en profunditat els projectes i traject\u00f2ries dels clients i col\u00b7laboradors. &nbsp; Fa gaireb\u00e9&hellip;<\/p>\n","protected":false},"author":3,"featured_media":2879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[110,105],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social\" \/>\n<meta property=\"og:description\" content=\"El gerent de Remm Guitart Xavier Mas ha protagonitzat la quarta trobada de Zip Zap En Forma, una iniciativa perqu\u00e8 el nostre equip conegui de prop i en profunditat els projectes i traject\u00f2ries dels clients i col\u00b7laboradors. &nbsp; Fa gaireb\u00e9&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/\" \/>\n<meta property=\"og:site_name\" content=\"ZipZap Social\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-24T15:55:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-24T15:56:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1284\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"David\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zipzapsocial.com\/#website\",\"url\":\"https:\/\/zipzapsocial.com\/\",\"name\":\"ZipZap Social\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zipzapsocial.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#primaryimage\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg\",\"contentUrl\":\"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg\",\"width\":1284,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#webpage\",\"url\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/\",\"name\":\"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social\",\"isPartOf\":{\"@id\":\"https:\/\/zipzapsocial.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#primaryimage\"},\"datePublished\":\"2019-04-24T15:55:42+00:00\",\"dateModified\":\"2019-04-24T15:56:04+00:00\",\"author\":{\"@id\":\"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1\"},\"breadcrumb\":{\"@id\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/zipzapsocial.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1\",\"name\":\"David\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zipzapsocial.com\/#personlogo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g\",\"caption\":\"David\"},\"url\":\"https:\/\/zipzapsocial.com\/ca\/author\/david\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/","og_locale":"ca_ES","og_type":"article","og_title":"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social","og_description":"El gerent de Remm Guitart Xavier Mas ha protagonitzat la quarta trobada de Zip Zap En Forma, una iniciativa perqu\u00e8 el nostre equip conegui de prop i en profunditat els projectes i traject\u00f2ries dels clients i col\u00b7laboradors. &nbsp; Fa gaireb\u00e9&hellip;","og_url":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/","og_site_name":"ZipZap Social","article_published_time":"2019-04-24T15:55:42+00:00","article_modified_time":"2019-04-24T15:56:04+00:00","og_image":[{"width":1284,"height":800,"url":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"David","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/zipzapsocial.com\/#website","url":"https:\/\/zipzapsocial.com\/","name":"ZipZap Social","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zipzapsocial.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"ImageObject","@id":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#primaryimage","inLanguage":"ca","url":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg","contentUrl":"https:\/\/zipzapsocial.com\/wp-content\/uploads\/2019\/04\/2404Web-Zip-Zap.jpg","width":1284,"height":800},{"@type":"WebPage","@id":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#webpage","url":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/","name":"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma - ZipZap Social","isPartOf":{"@id":"https:\/\/zipzapsocial.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#primaryimage"},"datePublished":"2019-04-24T15:55:42+00:00","dateModified":"2019-04-24T15:56:04+00:00","author":{"@id":"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1"},"breadcrumb":{"@id":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zipzapsocial.com\/ca\/el-negoci-dels-concessionaris-de-cotxes-centra-una-nova-trobada-de-zip-zap-en-forma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/zipzapsocial.com\/ca\/"},{"@type":"ListItem","position":2,"name":"El negoci dels concessionaris de cotxes centra una nova trobada de Zip Zap En Forma"}]},{"@type":"Person","@id":"https:\/\/zipzapsocial.com\/#\/schema\/person\/8e70e506ef950a7d5bb7b39d4fceb6d1","name":"David","image":{"@type":"ImageObject","@id":"https:\/\/zipzapsocial.com\/#personlogo","inLanguage":"ca","url":"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c95ce2af4fc4839f3ffe6fcbb0b0481b?s=96&d=mm&r=g","caption":"David"},"url":"https:\/\/zipzapsocial.com\/ca\/author\/david\/"}]}},"_links":{"self":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2881\/"}],"collection":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/comments\/?post=2881"}],"version-history":[{"count":1,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2881\/revisions\/"}],"predecessor-version":[{"id":2882,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/posts\/2881\/revisions\/2882\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/media\/2879\/"}],"wp:attachment":[{"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/media\/?parent=2881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/categories\/?post=2881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zipzapsocial.com\/ca\/wp-json\/wp\/v2\/tags\/?post=2881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}